{"id":3025,"date":"2012-06-11T12:02:48","date_gmt":"2012-06-11T10:02:48","guid":{"rendered":"http:\/\/sites.cardenalcisneros.es\/ciudadarte\/?p=3025"},"modified":"2012-06-11T12:02:48","modified_gmt":"2012-06-11T10:02:48","slug":"pamplona-171","status":"publish","type":"post","link":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/","title":{"rendered":"PAMPLONA (Nicol\u00e1s de Fer, 1719)"},"content":{"rendered":"<p><a href=\"http:\/\/cmapserver.unavarra.es\/servlet\/SBReadResourceServlet?rid=1167899159978_1820319873_9663\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-3026\" src=\"http:\/\/sites.cardenalcisneros.es\/ciudadarte\/wp-content\/uploads\/2012\/06\/Pamplona.jpg\" alt=\"\" width=\"599\" height=\"433\" \/><\/a><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">Este plano de Pamplona analizado fue realizado por Nicolas de Fer (1646-1720) en 1719. Nicolas de Fer, ge\u00f3grafo del Rey de Francia, cart\u00f3grafo, editor y grabador franc\u00e9s, se hizo cargo de la empresa iniciada por su padre Antoine De Fer, comerciante de grabados y mapas, publicando cientos de planos y mapas, adem\u00e1s de compilaciones en diversos atlas.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">Pamplona aparece aqu\u00ed como una ciudad preindustrial, una ciudad fortaleza emplazada en una terraza sobre el r\u00edo Arga, hacia el norte de la cuenca que lleva su nombre. Su situaci\u00f3n con relaci\u00f3n al entorno geogr\u00e1fico vino definida por razones de tipo pol\u00edtico, econ\u00f3mico y estrat\u00e9gico-militar, al estar situada en una importante ruta hacia Francia y en la ruta de Roncesvalles del Camino de Santiago. El<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">emplazamiento o espacio concreto sobre el que se asienta era fundamentalmente defensivo, claramente adaptado a la topograf\u00eda, para as\u00ed dominar la cuenca que le rodea y facilitar su defensa, siendo necesaria la construcci\u00f3n de un \u00fanico tramo de muralla. La ciudad se asoma por un talud de gran pendiente, y estaba rodeada, en su origen, por tierras de cultivo.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">Lo m\u00e1s destacable de la Pamplona medieval es su configuraci\u00f3n en tres burgos o n\u00facleos urbanos, Navarrer\u00eda, Burgo de San Cernin y Poblaci\u00f3n de San Nicol\u00e1s, con sus murallas, torres y portales independientes. El n\u00facleo primitivo era la Navarrer\u00eda, en torno a la catedral, con una estructura reticular en planta de cruz, y poblado por vascones labradores y por servidores de la catedral; se configur\u00f3 como ciudad episcopal. A mediados del siglo XI, al ser Pamplona una escala importante del Camino de Santiago, se asentaron en la ciudad, fundando el Burgo de San Cernin (con forma de hex\u00e1gono irregular), comerciantes y artesanos franceses. La ciudad se expandi\u00f3 al sur de este burgo<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">en la llamada Poblaci\u00f3n de San Nicol\u00e1s, con trazado de planta rectangular al modo de las bastidas francesas, una calle mayor central orientada de noreste a suroeste, iglesia y belena perpendicular, con una mezcla heterog\u00e9nea de habitantes, franceses y campesinos aut\u00f3ctonos, y sometido al poder episcopal.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">Los tres burgos eran recintos fortificados aislados, con sus propios portales y murallas, cuyo centro vital eran las iglesias, que adem\u00e1s desempe\u00f1aban un importante papel defensivo. Las contiendas entre ellos se sucedieron en la llamada \u201ctierra de nadie\u201d, hasta que se produjo la unificaci\u00f3n de los burgos en una sola ciudad en 1423, con una \u00fanica autoridad municipal e instituciones comunes, y se derribaron las murallas que aislaban y proteg\u00edan cada una de las poblaciones. Pamplona se convierte as\u00ed en una plaza militar, en un rect\u00e1ngulo amurallado de trazado irregular, y se edificaron las zonas correspondientes a los fosos de separaci\u00f3n entre los tres burgos, construyendo en su confluencia edificios dotacionales como el ayuntamiento o la alh\u00f3ndiga para cereales, as\u00ed como las plazas m\u00e1s importantes.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">La Plaza del Castillo, centro neur\u00e1lgico de Pamplona, se construy\u00f3 al estilo de las de la Edad Moderna, en 1545, rectangular, con arcadas, y para uso p\u00fablico: en ella se celebraban las corridas de toros antes de construirse una plaza fija. A finales del siglo XV se construye y\/o reconstruye el recinto amurallado externo com\u00fan. Con la anexi\u00f3n a Castilla en 1512, Pamplona se convierte en un enclave estrat\u00e9gico para impedir una posible invasi\u00f3n francesa, por lo que, en 1571, Felipe II ordena edificar la Ciudadela, siguiendo el modelo de la arquitectura militar renacentista de Amberes y Tur\u00edn, con forma pentagonal (estrella de cinco puntas, cinco baluartes), as\u00ed como reconstruir y perfeccionar las murallas, uni\u00e9ndolas con las antiguas del lado norte, y construyendo baluartes, bastiones, contraguardias, medias lunas, revellines y fuertes, lo que provoc\u00f3 que la ciudad \u00fanicamente pudiera desarrollarse en vertical. As\u00ed fue hasta la demolici\u00f3n de dos baluartes de la Ciudadela, para edificar el Primer Ensanche (1888), todav\u00eda dentro del recinto, y el derribo de la parte sur de la muralla, para dar lugar al Segundo Ensanche (1925), lo que facilit\u00f3 su expansi\u00f3n definitiva.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">En el siglo XVIII, cuando fue realizado este plano, Pamplona era al mismo tiempo una importante plaza militar, por su cercan\u00eda a Francia, y una ciudad conventual. Adem\u00e1s de la catedral y las cuatro antiguas parroquias, exist\u00edan gran cantidad de conventos en toda la ciudad, algunos de los cuales cambiaron de emplazamiento por la renovaci\u00f3n de sus edificios. Otras construcciones religiosas eran las bas\u00edlicas y las ermitas, lugares de romer\u00edas, unas dentro de las murallas y otras extramuros. Exist\u00edan adem\u00e1s edificios dedicados a la beneficencia para recoger mendigos y vagabundos de origen navarro (Hospital General de la Misericordia) o para ni\u00f1os hu\u00e9rfanos (Casa de los Ni\u00f1os de la Doctrina), adem\u00e1s de otros hospitales ligados a instituciones religiosas.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">Pamplona era adem\u00e1s capital del Reino de Navarra, con instituciones propias, por tanto, una ciudad administrativa cabeza de un obispado: dispon\u00eda de edificios civiles para sus \u00f3rganos de gobierno, como el Palacio del Virrey, el Palacio Episcopal, la sede del Consejo Real, la C\u00e1mara de Comptos o la Real Corte, adem\u00e1s del Ayuntamiento y de las c\u00e1rceles reales. As\u00ed, exist\u00eda un gran n\u00famero de religiosos dedicados a la labor pastoral, la oraci\u00f3n, la educaci\u00f3n y la sanidad, adem\u00e1s de una cantidad considerable de funcionarios. En el estado llano tambi\u00e9n abundaban los agricultores, artesanos (tejedores, cordeleros, alpargateros, hojalateros, cerrajeros, carpinteros, zapateros), industriales (molineros, cereros), militares de baja graduaci\u00f3n, personas dedicadas a la hosteler\u00eda y al servicio dom\u00e9stico y, sobre todo, comerciantes y hombres de negocios, siendo la capital sede de una importante feria anual, por su situaci\u00f3n geogr\u00e1fica y su sistema aduanero.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">La poblaci\u00f3n se mantuvo estable en n\u00famero desde mediados del siglo XVI hasta finales del siglo XVIII, y se distribu\u00eda en casas de viviendas intramuros en torno a las parroquias, adem\u00e1s de algunos hornos y molinos en las tierras circundantes. A finales del siglo XVIII, Pamplona contaba con 1632 casas, divididas en veinte barrios, 2812 vecinos y 14054 almas, tal como se dec\u00eda. La mayor\u00eda de habitantes viv\u00edan alquilados, puesto que las casas eran propiedad de nobles y burgueses o de instituciones religiosas, que invert\u00edan en bienes inmuebles. Se alquilaban las viviendas por pisos o por habitaciones, mezcl\u00e1ndose as\u00ed los habitantes de diferentes profesiones y extractos sociales (nobles, burgueses, funcionarios, comerciantes o artesanos).<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">En el siglo XVIII se fueron sustituyendo las viejas casas medievales y del siglo XVI por nuevas casas de cuatro, cinco y hasta seis alturas, con balcones a la calle, m\u00e1s sanas y ventiladas. En esta \u00e9poca no se modific\u00f3 la estructura urbana pero s\u00ed la morfolog\u00eda, convirti\u00e9ndose en una ciudad moderna con la llegada del alcantarillado, el agua corriente, las fuentes y el alumbrado p\u00fablico. Las calles eran m\u00e1s rectas y despejadas, y se pavimentaron con empedrado y losas para las aceras.<\/span><\/p>\n<p style=\"text-align: justify\" align=\"left\"><span style=\"color: #000000\">Y en lo referente a la vida cotidiana, se celebraban frecuentemente fiestas tanto religiosas como profanas (cortejos, desfiles, procesiones, teatros, m\u00e1scaras, corridas de toros), por las que la ciudad se engalanaba; se erig\u00edan arcos triunfales, t\u00edpicos de la \u00e9poca barroca, y se conmemoraban los acontecimientos relacionados con la familia real (visitas, matrimonios, nacimientos). Hab\u00eda adem\u00e1s jardines como la Taconera y plazas como la Plaza del Castillo o la Plaza de la Fruta, que\u00a0eran muyconcurridos como lugares de esparcimiento.<\/span><\/p>\n<p style=\"text-align: justify\">Eva Mar\u00eda Garc\u00eda Caba\u00f1as<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este plano de Pamplona analizado fue realizado por Nicolas de Fer (1646-1720) en 1719. Nicolas de Fer, ge\u00f3grafo del Rey de Francia, cart\u00f3grafo, editor y grabador franc\u00e9s, se hizo cargo de la empresa iniciada por su padre Antoine De Fer, comerciante de grabados y mapas, publicando cientos de planos y mapas, adem\u00e1s de compilaciones en [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[161],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAMPLONA (Nicol\u00e1s de Fer, 1719) - La Ciudad en el Arte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAMPLONA (Nicol\u00e1s de Fer, 1719) - La Ciudad en el Arte\" \/>\n<meta property=\"og:description\" content=\"Este plano de Pamplona analizado fue realizado por Nicolas de Fer (1646-1720) en 1719. Nicolas de Fer, ge\u00f3grafo del Rey de Francia, cart\u00f3grafo, editor y grabador franc\u00e9s, se hizo cargo de la empresa iniciada por su padre Antoine De Fer, comerciante de grabados y mapas, publicando cientos de planos y mapas, adem\u00e1s de compilaciones en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/\" \/>\n<meta property=\"og:site_name\" content=\"La Ciudad en el Arte\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-11T10:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sites.cardenalcisneros.es\/ciudadarte\/wp-content\/uploads\/2012\/06\/Pamplona.jpg\" \/>\n<meta name=\"author\" content=\"Alumno Campus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alumno Campus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/\",\"url\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/\",\"name\":\"PAMPLONA (Nicol\u00e1s de Fer, 1719) - La Ciudad en el Arte\",\"isPartOf\":{\"@id\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#website\"},\"datePublished\":\"2012-06-11T10:02:48+00:00\",\"dateModified\":\"2012-06-11T10:02:48+00:00\",\"author\":{\"@id\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#\/schema\/person\/0f83c64b2a28c1a5a38f7d9dd2e38fc2\"},\"breadcrumb\":{\"@id\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAMPLONA (Nicol\u00e1s de Fer, 1719)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#website\",\"url\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/\",\"name\":\"La Ciudad en el Arte\",\"description\":\"Un blog colaborativo sobre Geograf\u00eda, Urbanismo, Historia y Arte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#\/schema\/person\/0f83c64b2a28c1a5a38f7d9dd2e38fc2\",\"name\":\"Alumno Campus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/451448e807ff33883635030571ef263a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/451448e807ff33883635030571ef263a?s=96&d=mm&r=g\",\"caption\":\"Alumno Campus\"},\"url\":\"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/author\/alumnocampus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAMPLONA (Nicol\u00e1s de Fer, 1719) - La Ciudad en el Arte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/","og_locale":"es_ES","og_type":"article","og_title":"PAMPLONA (Nicol\u00e1s de Fer, 1719) - La Ciudad en el Arte","og_description":"Este plano de Pamplona analizado fue realizado por Nicolas de Fer (1646-1720) en 1719. Nicolas de Fer, ge\u00f3grafo del Rey de Francia, cart\u00f3grafo, editor y grabador franc\u00e9s, se hizo cargo de la empresa iniciada por su padre Antoine De Fer, comerciante de grabados y mapas, publicando cientos de planos y mapas, adem\u00e1s de compilaciones en [&hellip;]","og_url":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/","og_site_name":"La Ciudad en el Arte","article_published_time":"2012-06-11T10:02:48+00:00","og_image":[{"url":"http:\/\/sites.cardenalcisneros.es\/ciudadarte\/wp-content\/uploads\/2012\/06\/Pamplona.jpg"}],"author":"Alumno Campus","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alumno Campus","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/","url":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/","name":"PAMPLONA (Nicol\u00e1s de Fer, 1719) - La Ciudad en el Arte","isPartOf":{"@id":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#website"},"datePublished":"2012-06-11T10:02:48+00:00","dateModified":"2012-06-11T10:02:48+00:00","author":{"@id":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#\/schema\/person\/0f83c64b2a28c1a5a38f7d9dd2e38fc2"},"breadcrumb":{"@id":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/2012\/06\/11\/pamplona-171\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/"},{"@type":"ListItem","position":2,"name":"PAMPLONA (Nicol\u00e1s de Fer, 1719)"}]},{"@type":"WebSite","@id":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#website","url":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/","name":"La Ciudad en el Arte","description":"Un blog colaborativo sobre Geograf\u00eda, Urbanismo, Historia y Arte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#\/schema\/person\/0f83c64b2a28c1a5a38f7d9dd2e38fc2","name":"Alumno Campus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/451448e807ff33883635030571ef263a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/451448e807ff33883635030571ef263a?s=96&d=mm&r=g","caption":"Alumno Campus"},"url":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/author\/alumnocampus\/"}]}},"_links":{"self":[{"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/posts\/3025"}],"collection":[{"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/comments?post=3025"}],"version-history":[{"count":0,"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/posts\/3025\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/media?parent=3025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/categories?post=3025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.cardenalcisneros.es\/ciudadarte\/index.php\/wp-json\/wp\/v2\/tags?post=3025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}